{"id":591,"count":1,"description":"","link":"https:\/\/pangolinonline.com\/en\/category\/safety_clothing\/","name":"\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e17\u0e32\u0e07\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e0a\u0e38\u0e14\u0e01\u0e31\u0e19\u0e2a\u0e32\u0e23\u0e40\u0e04\u0e21\u0e35","slug":"safety_clothing","taxonomy":"category","parent":0,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/pangolinonline.com\/en\/wp-json\/wp\/v2\/categories\/591","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pangolinonline.com\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/pangolinonline.com\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/pangolinonline.com\/en\/wp-json\/wp\/v2\/posts?categories=591"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}